{"id":1386,"date":"2024-07-01T06:05:31","date_gmt":"2024-07-01T04:05:31","guid":{"rendered":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/?p=1386"},"modified":"2024-12-04T10:39:12","modified_gmt":"2024-12-04T09:39:12","slug":"willkommen_henry","status":"publish","type":"post","link":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/willkommen_henry\/","title":{"rendered":"Neuer Physiotherapeut HENRY!"},"content":{"rendered":"<p><strong>Willkommen im Team, Henry Bernhard!<\/strong><\/p>\n<p>Heute, am 1. Juli, freuen wir uns sehr, unseren neuen Kollegen Henry Bernhardt bei uns willkommen zu hei\u00dfen. Mit gro\u00dfer Freude begr\u00fc\u00dfen wir ihn in unserem Team und sind gespannt auf die gemeinsame Zeit, die vor uns liegt.<\/p>\n<p>Henry bringt nicht nur viel Fachwissen und Erfahrung mit, sondern auch eine Leidenschaft f\u00fcr die Physiotherapie, die uns alle bereichern wird. Sein Engagement und seine Expertise werden unsere Praxis weiter st\u00e4rken und Ihnen, liebe Patientinnen und Patienten, zugutekommen.<\/p>\n<p>Wir freuen uns auf eine erfolgreiche Zusammenarbeit und viele gemeinsame Erfolge.<\/p>\n<p>Ihr Team der Physiotherapie Am Spittelberg<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen im Team, Henry Bernhard! Heute, am 1. Juli, freuen wir uns sehr, unseren neuen Kollegen Henry Bernhardt bei uns willkommen zu hei\u00dfen. Mit gro\u00dfer Freude begr\u00fc\u00dfen wir ihn in unserem Team und sind gespannt auf die gemeinsame Zeit, die vor uns liegt. Henry bringt nicht nur viel Fachwissen und Erfahrung mit, sondern auch eine [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1386","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts\/1386","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/comments?post=1386"}],"version-history":[{"count":2,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts\/1386\/revisions"}],"predecessor-version":[{"id":1443,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts\/1386\/revisions\/1443"}],"wp:attachment":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/media?parent=1386"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/categories?post=1386"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/tags?post=1386"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}