{"id":1419,"date":"2024-09-11T09:33:13","date_gmt":"2024-09-11T07:33:13","guid":{"rendered":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/?p=1419"},"modified":"2024-09-11T09:33:13","modified_gmt":"2024-09-11T07:33:13","slug":"neue-physiotherapeutin-lucie","status":"publish","type":"post","link":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/neue-physiotherapeutin-lucie\/","title":{"rendered":"Neue Physiotherapeutin LUCIE!"},"content":{"rendered":"<p><strong>Willkommen im Team, Lucie Reichenbach!<\/strong><\/p>\n<p>Seit dem 1. September, freuen wir uns sehr, unsere neue Kollegin Lucie Reichenbach bei uns willkommen zu hei\u00dfen. Wir freuen uns sehr sie in unserem Team begr\u00fc\u00dfen zu d\u00fcrfen und sind gespannt auf die gemeinsame Zeit, die vor uns liegt.<\/p>\n<p>Wir freuen uns auf eine erfolgreiche Zusammenarbeit und viele gemeinsame Erfolge.<\/p>\n<p>Ihr Team der Physiotherapie Am Spittelberg<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Willkommen im Team, Lucie Reichenbach! Seit dem 1. September, freuen wir uns sehr, unsere neue Kollegin Lucie Reichenbach bei uns willkommen zu hei\u00dfen. Wir freuen uns sehr sie in unserem Team begr\u00fc\u00dfen zu d\u00fcrfen und sind gespannt auf die gemeinsame Zeit, die vor uns liegt. Wir freuen uns auf eine erfolgreiche Zusammenarbeit und viele gemeinsame [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"","_et_pb_old_content":"","_et_gb_content_width":"","inline_featured_image":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1419","post","type-post","status-publish","format-standard","hentry","category-news"],"_links":{"self":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts\/1419","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/comments?post=1419"}],"version-history":[{"count":1,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts\/1419\/revisions"}],"predecessor-version":[{"id":1420,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/posts\/1419\/revisions\/1420"}],"wp:attachment":[{"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/media?parent=1419"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/categories?post=1419"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/physiotherapie-am-spittelberg.de\/spittelberg\/wp-json\/wp\/v2\/tags?post=1419"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}